{"id":6785,"date":"2022-08-03T10:09:44","date_gmt":"2022-08-03T10:09:44","guid":{"rendered":"https:\/\/tritondispenser.com\/descargas\/protocolo-profesional-de-limpieza\/"},"modified":"2022-11-29T11:13:57","modified_gmt":"2022-11-29T11:13:57","slug":"protocolo-profesional-de-limpieza","status":"publish","type":"descargas","link":"https:\/\/tritondispenser.com\/fr\/descargas\/protocolo-profesional-de-limpieza\/","title":{"rendered":"1. Protocole de nettoyage professionnel"},"template":"","categoria_de_descargas":[156],"class_list":["post-6785","descargas","type-descargas","status-publish","hentry","categoria_de_descargas-02-classic-3l-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>1. Protocole de nettoyage professionnel - Tritondispenser<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tritondispenser.com\/fr\/descargas\/protocolo-profesional-de-limpieza\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1. Protocole de nettoyage professionnel - Tritondispenser\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tritondispenser.com\/fr\/descargas\/protocolo-profesional-de-limpieza\/\" \/>\n<meta property=\"og:site_name\" content=\"Tritondispenser\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-29T11:13:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tritondispenser.com\/fr\/descargas\/protocolo-profesional-de-limpieza\/\",\"url\":\"https:\/\/tritondispenser.com\/fr\/descargas\/protocolo-profesional-de-limpieza\/\",\"name\":\"1. Protocole de nettoyage professionnel - Tritondispenser\",\"isPartOf\":{\"@id\":\"https:\/\/tritondispenser.com\/#website\"},\"datePublished\":\"2022-08-03T10:09:44+00:00\",\"dateModified\":\"2022-11-29T11:13:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tritondispenser.com\/fr\/descargas\/protocolo-profesional-de-limpieza\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tritondispenser.com\/fr\/descargas\/protocolo-profesional-de-limpieza\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tritondispenser.com\/fr\/descargas\/protocolo-profesional-de-limpieza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/tritondispenser.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"1. Protocole de nettoyage professionnel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tritondispenser.com\/#website\",\"url\":\"https:\/\/tritondispenser.com\/\",\"name\":\"Tritondispenser\",\"description\":\"Dispensadores port\u00e1tiles de cerveza Tritondispenser, desde 1995\",\"publisher\":{\"@id\":\"https:\/\/tritondispenser.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tritondispenser.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tritondispenser.com\/#organization\",\"name\":\"Tritondispenser\",\"url\":\"https:\/\/tritondispenser.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/tritondispenser.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tritondispenser.com\/wp-content\/uploads\/2022\/07\/logo-triton.svg\",\"contentUrl\":\"https:\/\/tritondispenser.com\/wp-content\/uploads\/2022\/07\/logo-triton.svg\",\"width\":1,\"height\":1,\"caption\":\"Tritondispenser\"},\"image\":{\"@id\":\"https:\/\/tritondispenser.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1. Protocole de nettoyage professionnel - Tritondispenser","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tritondispenser.com\/fr\/descargas\/protocolo-profesional-de-limpieza\/","og_locale":"fr_FR","og_type":"article","og_title":"1. Protocole de nettoyage professionnel - Tritondispenser","og_url":"https:\/\/tritondispenser.com\/fr\/descargas\/protocolo-profesional-de-limpieza\/","og_site_name":"Tritondispenser","article_modified_time":"2022-11-29T11:13:57+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tritondispenser.com\/fr\/descargas\/protocolo-profesional-de-limpieza\/","url":"https:\/\/tritondispenser.com\/fr\/descargas\/protocolo-profesional-de-limpieza\/","name":"1. Protocole de nettoyage professionnel - Tritondispenser","isPartOf":{"@id":"https:\/\/tritondispenser.com\/#website"},"datePublished":"2022-08-03T10:09:44+00:00","dateModified":"2022-11-29T11:13:57+00:00","breadcrumb":{"@id":"https:\/\/tritondispenser.com\/fr\/descargas\/protocolo-profesional-de-limpieza\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tritondispenser.com\/fr\/descargas\/protocolo-profesional-de-limpieza\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tritondispenser.com\/fr\/descargas\/protocolo-profesional-de-limpieza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tritondispenser.com\/"},{"@type":"ListItem","position":2,"name":"1. Protocole de nettoyage professionnel"}]},{"@type":"WebSite","@id":"https:\/\/tritondispenser.com\/#website","url":"https:\/\/tritondispenser.com\/","name":"Tritondispenser","description":"Dispensadores port\u00e1tiles de cerveza Tritondispenser, desde 1995","publisher":{"@id":"https:\/\/tritondispenser.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tritondispenser.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/tritondispenser.com\/#organization","name":"Tritondispenser","url":"https:\/\/tritondispenser.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/tritondispenser.com\/#\/schema\/logo\/image\/","url":"https:\/\/tritondispenser.com\/wp-content\/uploads\/2022\/07\/logo-triton.svg","contentUrl":"https:\/\/tritondispenser.com\/wp-content\/uploads\/2022\/07\/logo-triton.svg","width":1,"height":1,"caption":"Tritondispenser"},"image":{"@id":"https:\/\/tritondispenser.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/tritondispenser.com\/fr\/wp-json\/wp\/v2\/descargas\/6785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tritondispenser.com\/fr\/wp-json\/wp\/v2\/descargas"}],"about":[{"href":"https:\/\/tritondispenser.com\/fr\/wp-json\/wp\/v2\/types\/descargas"}],"wp:attachment":[{"href":"https:\/\/tritondispenser.com\/fr\/wp-json\/wp\/v2\/media?parent=6785"}],"wp:term":[{"taxonomy":"categoria_de_descargas","embeddable":true,"href":"https:\/\/tritondispenser.com\/fr\/wp-json\/wp\/v2\/categoria_de_descargas?post=6785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}